{"id":18158,"date":"2026-07-15T05:10:52","date_gmt":"2026-07-15T03:10:52","guid":{"rendered":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/"},"modified":"2026-07-15T05:10:53","modified_gmt":"2026-07-15T03:10:53","slug":"cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace","status":"publish","type":"post","link":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/","title":{"rendered":"C&rsquo;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace"},"content":{"rendered":"<p><!--$--><br \/>\n<!--\/--><br \/>\n<!--$--><\/p>\n<div data-hk=\"0000a104212000a23100\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<p>Le savez-vous aussi ? Vous mangez joyeusement de la glace et tout d&rsquo;un coup, une vive douleur vous envahit le front, presque comme si votre cerveau \u00e9tait gel\u00e9. En fait, ce mal de t\u00eate d\u00fb au froid est \u00e9galement appel\u00e9 gel du cerveau. Mais d\u2019o\u00f9 vient ce qu\u2019on appelle le \u00ab gel du cerveau \u00bb et que pouvez-vous faire pour y rem\u00e9dier ?<\/p>\n<\/div>\n<div data-hk=\"0000a104212000a23110\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<p>Selon une \u00e9tude canadienne, une personne sur trois est sujette \u00e0 ce mal de t\u00eate d\u00e9sagr\u00e9able lorsqu&rsquo;elle mange de la glace ou boit des boissons glac\u00e9es. Essentiellement, cette r\u00e9action au froid dans la bouche est le m\u00e9canisme de protection naturel de votre corps. Plus la glace ou la boisson est froide, plus votre corps r\u00e9agit violemment.<\/p>\n<\/div>\n<aside data-hk=\"0000a104212000a231204\" data-qa-ad-slot class=\"Ad-Slot Ad-Slot-mobile Ad-Slot-hor Ad-Slot-FC\">\n<div class=\"Ad-Slot-FC-Container\">\n<div class=\"Ad-Slot-FC-Window\">\n<div id=\"ad-slot-mobile-hor-2\" data-orientation=\"hor\" data-index=\"2\" data-slot=\"ad-slot\" data-device=\"mobile\"><\/div>\n<\/div>\n<\/div>\n<\/aside>\n<div data-hk=\"0000a104212000a23130\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<h2>Maux de t\u00eate froids\u00a0: c&rsquo;est ce qui se cache derri\u00e8re<\/h2>\n<p>Si vous mangez quelque chose de congel\u00e9, les vaisseaux sanguins de votre gorge et de votre palais se contracteront pour emp\u00eacher la temp\u00e9rature de votre corps de baisser. En m\u00eame temps, le sang afflue vers votre cerveau pour compenser le froid. Le flux sanguin rapide augmente la pression dans les vaisseaux sanguins. Cela conduit \u00e0 une douleur soudaine et lancinante dans la r\u00e9gion du front. On a presque l&rsquo;impression que votre cerveau se fige. Mais ne vous inqui\u00e9tez pas : le mal de t\u00eate d\u00fb au froid est d\u00e9sagr\u00e9able, mais pas dangereux.<\/p>\n<\/div>\n<aside data-hk=\"0000a104212000a231404\" data-qa-ad-slot class=\"Ad-Slot Ad-Slot-mobile Ad-Slot-out\">\n<div id=\"ad-slot-mobile-out-1\" data-orientation=\"out\" data-index=\"1\" data-slot=\"ad-slot\" data-device=\"mobile\"><\/div>\n<\/aside>\n<div data-hk=\"0000a104212000a23150\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<h2>Comment \u00e9viter le gel du cerveau en mangeant de la glace<\/h2>\n<p>Le mal de t\u00eate lancinant survient lorsque quelque chose de tr\u00e8s froid entre en contact avec le palais. Si vous voulez \u00e9viter le gel ennuyeux du cerveau, consommez uniquement des aliments et des boissons froids lentement et en petites quantit\u00e9s. Il est \u00e9galement utile de tourner la cuill\u00e8re de mani\u00e8re \u00e0 ce qu&rsquo;elle se trouve entre le palais de votre bouche et la glace lorsque vous mangez de la glace. Attendez que la glace ait fondu sur votre langue avant d&rsquo;avaler.<\/p>\n<\/div>\n<aside data-hk=\"0000a104212000a231604\" data-qa-ad-slot class=\"Ad-Slot Ad-Slot-mobile Ad-Slot-hor\">\n<div id=\"ad-slot-mobile-hor-3\" data-orientation=\"hor\" data-index=\"3\" data-slot=\"ad-slot\" data-device=\"mobile\"><\/div>\n<\/aside>\n<div data-hk=\"0000a104212000a23170\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<p>Si la douleur est d\u00e9j\u00e0 apparue, il sera utile de placer votre propre langue sur le palais. Ou vous pouvez ensuite boire lentement un verre d\u2019eau ti\u00e8de. Avec ces m\u00e9thodes, la douleur lancinante dispara\u00eetra plus rapidement. Si vous \u00eates sujet aux maux de t\u00eate dus au froid, \u00e9vitez compl\u00e8tement les gla\u00e7ons dans votre boisson.<\/p>\n<\/div>\n<div data-hk=\"0000a104212000a23180\" class=\"Html-Block\" data-qa-article-content-text data-text-milestone-block>\n<p>\u00c0 propos : vous pouvez vous \u00e9pargner un comprim\u00e9 contre les maux de t\u00eate si votre cerveau se fige. Au moment o\u00f9 l\u2019analg\u00e9sique fait effet, le mal de t\u00eate aura presque certainement disparu et la glace aura fondu. Les maux de t\u00eate dus au froid ne durent g\u00e9n\u00e9ralement que quelques secondes. <\/p>\n<\/div>\n<p><!--\/--><br \/>\n<!--$--><br \/>\n<!--\/--><br \/>\n<!--$--><br \/>\n<!--\/--><br \/>\n<!--$--><br \/>\n<!--\/--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le savez-vous aussi ? Vous mangez joyeusement de la glace et tout d&rsquo;un coup, une<\/p>\n","protected":false},"author":1,"featured_media":18159,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[3452,4747,94,8015,2500,2019,6903,3633],"class_list":["post-18158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-maladies","tag-cest","tag-glace","tag-mal","tag-mange","tag-parfois","tag-pourquoi","tag-quand","tag-tete","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C&#039;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C&#039;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org\" \/>\n<meta property=\"og:description\" content=\"Le savez-vous aussi ? Vous mangez joyeusement de la glace et tout d&rsquo;un coup, une\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\" \/>\n<meta property=\"og:site_name\" content=\"RVH-Synergie\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T03:10:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T03:10:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\"},\"author\":{\"name\":\"Charles Martinez\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/6affb9c7fc596daaea315c8c28318135\"},\"headline\":\"C&rsquo;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace\",\"datePublished\":\"2026-07-15T03:10:52+00:00\",\"dateModified\":\"2026-07-15T03:10:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\"},\"wordCount\":471,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#organization\"},\"image\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg\",\"keywords\":[\"Cest\",\"glace\",\"mal\",\"mang\u00e9\",\"parfois\",\"Pourquoi\",\"quand\",\"t\u00eate\"],\"articleSection\":[\"Les maladies\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\",\"name\":\"C'est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org\",\"isPartOf\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg\",\"datePublished\":\"2026-07-15T03:10:52+00:00\",\"dateModified\":\"2026-07-15T03:10:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg\",\"contentUrl\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/rvh-synergie.org\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C&rsquo;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#website\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/\",\"name\":\"RVH-Synergie.org\",\"description\":\"RVH-Synergie, site ind\u00e9pendant d&#039;informations sur la prise en charge des addictions.\",\"publisher\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rvh-synergie.org\/actualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#organization\",\"name\":\"RVH-Synergie.org\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/favicon.png\",\"contentUrl\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"RVH-Synergie.org\"},\"image\":{\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/6affb9c7fc596daaea315c8c28318135\",\"name\":\"Charles Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/charles-martinez-scaled.jpg\",\"contentUrl\":\"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/charles-martinez-scaled.jpg\",\"caption\":\"Charles Martinez\"},\"description\":\"Bonjour, je m'appelle Charles Martinez, r\u00e9dacteur passionn\u00e9 pour le m\u00e9dia RVH-synergie.org, d\u00e9di\u00e9 aux addictions et aux maladies. Depuis plus de dix ans, j'explore et rapporte les histoires poignantes des individus confront\u00e9s \u00e0 ces d\u00e9fis, tout en sensibilisant le public aux traitements novateurs et aux progr\u00e8s scientifiques dans ce domaine. Mon engagement r\u00e9side dans l'espoir de cr\u00e9er une communaut\u00e9 inform\u00e9e et empathique, pr\u00eate \u00e0 soutenir ceux qui luttent contre ces \u00e9preuves.\",\"sameAs\":[\"https:\/\/rvh-synergie.org\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C'est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/","og_locale":"fr_FR","og_type":"article","og_title":"C'est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org","og_description":"Le savez-vous aussi ? Vous mangez joyeusement de la glace et tout d&rsquo;un coup, une","og_url":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/","og_site_name":"RVH-Synergie","article_published_time":"2026-07-15T03:10:52+00:00","article_modified_time":"2026-07-15T03:10:53+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg","type":"image\/jpeg"}],"author":"Charles Martinez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Charles Martinez","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#article","isPartOf":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/"},"author":{"name":"Charles Martinez","@id":"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/6affb9c7fc596daaea315c8c28318135"},"headline":"C&rsquo;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace","datePublished":"2026-07-15T03:10:52+00:00","dateModified":"2026-07-15T03:10:53+00:00","mainEntityOfPage":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/"},"wordCount":471,"commentCount":0,"publisher":{"@id":"https:\/\/rvh-synergie.org\/actualites\/#organization"},"image":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage"},"thumbnailUrl":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg","keywords":["Cest","glace","mal","mang\u00e9","parfois","Pourquoi","quand","t\u00eate"],"articleSection":["Les maladies"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/","url":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/","name":"C'est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace - RVH-Synergie.org","isPartOf":{"@id":"https:\/\/rvh-synergie.org\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage"},"image":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage"},"thumbnailUrl":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg","datePublished":"2026-07-15T03:10:52+00:00","dateModified":"2026-07-15T03:10:53+00:00","breadcrumb":{"@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#primaryimage","url":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg","contentUrl":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2026\/07\/Cest-pourquoi-parfois-on-a-mal-a-la-tete-quand.jpeg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/rvh-synergie.org\/actualites\/cest-pourquoi-parfois-on-a-mal-a-la-tete-quand-on-mange-de-la-glace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rvh-synergie.org\/actualites\/"},{"@type":"ListItem","position":2,"name":"C&rsquo;est pourquoi parfois on a mal \u00e0 la t\u00eate quand on mange de la glace"}]},{"@type":"WebSite","@id":"https:\/\/rvh-synergie.org\/actualites\/#website","url":"https:\/\/rvh-synergie.org\/actualites\/","name":"RVH-Synergie.org","description":"RVH-Synergie, site ind\u00e9pendant d&#039;informations sur la prise en charge des addictions.","publisher":{"@id":"https:\/\/rvh-synergie.org\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rvh-synergie.org\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rvh-synergie.org\/actualites\/#organization","name":"RVH-Synergie.org","url":"https:\/\/rvh-synergie.org\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/favicon.png","contentUrl":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/favicon.png","width":512,"height":512,"caption":"RVH-Synergie.org"},"image":{"@id":"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/6affb9c7fc596daaea315c8c28318135","name":"Charles Martinez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rvh-synergie.org\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/charles-martinez-scaled.jpg","contentUrl":"https:\/\/rvh-synergie.org\/actualites\/wp-content\/uploads\/2024\/09\/charles-martinez-scaled.jpg","caption":"Charles Martinez"},"description":"Bonjour, je m'appelle Charles Martinez, r\u00e9dacteur passionn\u00e9 pour le m\u00e9dia RVH-synergie.org, d\u00e9di\u00e9 aux addictions et aux maladies. Depuis plus de dix ans, j'explore et rapporte les histoires poignantes des individus confront\u00e9s \u00e0 ces d\u00e9fis, tout en sensibilisant le public aux traitements novateurs et aux progr\u00e8s scientifiques dans ce domaine. Mon engagement r\u00e9side dans l'espoir de cr\u00e9er une communaut\u00e9 inform\u00e9e et empathique, pr\u00eate \u00e0 soutenir ceux qui luttent contre ces \u00e9preuves.","sameAs":["https:\/\/rvh-synergie.org\/"]}]}},"_links":{"self":[{"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/posts\/18158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/comments?post=18158"}],"version-history":[{"count":1,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/posts\/18158\/revisions"}],"predecessor-version":[{"id":18160,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/posts\/18158\/revisions\/18160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/media\/18159"}],"wp:attachment":[{"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/media?parent=18158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/categories?post=18158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rvh-synergie.org\/actualites\/wp-json\/wp\/v2\/tags?post=18158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}